{"id":2207,"date":"2025-09-24T17:27:59","date_gmt":"2025-09-24T15:27:59","guid":{"rendered":"https:\/\/www.revelomallorca.es\/revelo-about-us\/"},"modified":"2025-10-24T12:21:38","modified_gmt":"2025-10-24T10:21:38","slug":"revelo-sobre-nosotros","status":"publish","type":"page","link":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/","title":{"rendered":"Revelo &#8211; Sobre nosotros"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb2524&#8243; bg_position=\u00bbcenter top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#263336&#8243; overlay_strength=\u00bb1&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bb\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb5\/12&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb.vc_custom_1759853979295{margin-top: 40px !important;margin-bottom: 5px !important;}\u00bb text_direction=\u00bbdefault\u00bb]\n<h5>Mira dentro<\/h5>\n[\/vc_column_text][nectar_highlighted_text color_type=\u00bbregular\u00bb highlight_color=\u00bb#ff1053&#8243; style=\u00bbhalf_text\u00bb text_direction=\u00bbdefault\u00bb]\n<h1>Bienvenidos a <em>Revelo Mallorca<\/em>, un espacio dedicado al ciclismo y a estar juntos.<\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][\/vc_row_inner][nectar_video_lightbox link_style=\u00bbplay_button\u00bb video_url=\u00bbhttps:\/\/www.revelomallorca.es\/wp-content\/uploads\/2025\/10\/revelo-2.mp4&#8243;][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb7\/12&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_margin=\u00bb16&#8243; bottom_margin=\u00bb16&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bbcurve\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<div class=\"bradcrumssite\"><span><span><a href=\"https:\/\/www.revelomallorca.es\/es\/\">Home<\/a><\/span><\/span><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbcolumn_reverse\u00bb bg_image=\u00bb1893&#8243; bg_position=\u00bbright top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb32&#8243; constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb32&#8243; left_padding_tablet=\u00bb8%\u00bb constrain_group_4=\u00bbyes\u00bb right_padding_tablet=\u00bb8%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb color_overlay=\u00bb#FFFFFF\u00bb advanced_gradient_angle=\u00bb0&#8243; overlay_strength=\u00bb0.95&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bb0px\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb right_padding_desktop=\u00bb20%\u00bb right_padding_tablet=\u00bb10%\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; background_image=\u00bb1762&#8243; background_image_position=\u00bbleft center\u00bb background_image_stacking=\u00bbdefault\u00bb enable_bg_scale=\u00bbtrue\u00bb background_image_loading=\u00bbdefault\u00bb column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bb20px\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbvery_subtle\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb90vh\u00bb custom_height_tablet=\u00bb70vh\u00bb custom_height_phone=\u00bb60vh\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb translate_y=\u00bb-50%\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbabsolute\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb top_position_desktop=\u00bb50%\u00bb right_position_desktop=\u00bb0&#8243; min_width_desktop=\u00bb40%\u00bb min_width_phone=\u00bb60%\u00bb zindex=\u00bb50&#8243; overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; background_image=\u00bb1878&#8243; background_image_position=\u00bbleft center\u00bb background_image_stacking=\u00bbdefault\u00bb enable_bg_scale=\u00bbtrue\u00bb background_image_loading=\u00bbdefault\u00bb column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbx_large_depth\u00bb column_border_radius=\u00bb20px\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbparallax\u00bb animation_movement_type=\u00bbdefault\u00bb column_parallax_intensity=\u00bb2.25&#8243; persist_movement_on_mobile=\u00bbtrue\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbvery_subtle\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb50vh\u00bb custom_height_tablet=\u00bb40vh\u00bb custom_height_phone=\u00bb35vh\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbpadding-8-percent\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbleft-right\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb advanced_gradient_angle=\u00bb0&#8243; gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb column_padding_type=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbnone\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb10&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<h5>REVELO MALLORCA<\/h5>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbh2&#8243; text_color=\u00bb#000000&#8243; line_reveal_by_space_text_effect=\u00bbdefault\u00bb stagger_animation=\u00bbtrue\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb link_target=\u00bb_self\u00bb text_content=\u00bbAventura, diversi\u00f3n y un toque de sana competici\u00f3n.\u00bb font_size=\u00bb3vw\u00bb text_direction=\u00bbdefault\u00bb][\/split_line_heading][vc_row_inner column_margin=\u00bbnone\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding_phone=\u00bb32&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbp\u00bb line_reveal_by_space_text_effect=\u00bbnone\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb link_target=\u00bb_self\u00bb text_content=\u00bbNacimos del amor por la exploraci\u00f3n y de las ganas de compartir la carretera \u2014 ya sea asfalto liso o caminos de gravel \u2014 con quienes buscan aventura, diversi\u00f3n y un toque de sana competici\u00f3n.<\/p>\n<p>Junto al caf\u00e9, encontrar\u00e1s comida saludable pero deliciosa, pensada para darte energ\u00eda sin renunciar al placer: opciones dulces y saladas, proteicas y energ\u00e9ticas, todas elaboradas por nosotros con ingredientes cuidadosamente seleccionados.<\/p>\n<p>Ya sea que est\u00e9s a punto de salir de ruta, acabes de entrenar o simplemente quieras disfrutar de una pausa sabrosa, aqu\u00ed siempre encontrar\u00e1s algo casero, nutritivo y hecho con pasi\u00f3n.\u00bb font_size=\u00bb1.1vw\u00bb font_line_height=\u00bb1.7&#8243; font_size_tablet=\u00bb18px\u00bb font_size_phone=\u00bb16px\u00bb text_direction=\u00bbdefault\u00bb][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbnone\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding_phone=\u00bb32&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb gradient_type=\u00bbdefault\u00bb][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbsee-through\u00bb button_color_2=\u00bbAccent-Color\u00bb icon_family=\u00bbdefault_arrow\u00bb text=\u00bbDescubra m\u00e1s sobre nosotros\u00bb url=\u00bbhttps:\/\/www.revelomallorca.es\/es\/quienes-somos-nuestra-historia-nuestra-pasion\/\u00bb margin_top=\u00bb32&#8243; css_animation=\u00bbfadeInUp\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#F7F7F7&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb2%\u00bb bottom_padding=\u00bb2%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_custom_heading text=\u00bbV\u00e9ase tambi\u00e9n\u00bb font_container=\u00bbtag:h1|font_size:48px|text_align:center|line_height:57px\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbnone\u00bb css=\u00bb\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb20&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_icon icon_family=\u00bbfontawesome\u00bb icon_style=\u00bbshadow-bg\u00bb icon_color_type=\u00bbcustom\u00bb icon_color_custom=\u00bb#000000&#8243; icon_color_custom_hover=\u00bb#DD3333&#8243; icon_padding=\u00bb20px\u00bb pointer_events=\u00bball\u00bb icon_fontawesome=\u00bbfa fa-bicycle\u00bb icon_size=\u00bb64&#8243; margin_bottom=\u00bb6&#8243;][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1759939240353{margin-top: 32px !important;margin-bottom: 15px !important;}\u00bb text_direction=\u00bbdefault\u00bb]\n<h5>Alquiler de bicicletas<\/h5>\n[\/vc_column_text][vc_custom_heading text=\u00bbBicicletas de carretera, gravel y el\u00e9ctricas de gravel\/carretera. \u00a1Solo la mejor calidad exclusiva!\u00bb font_container=\u00bbtag:p|text_align:center|color:rgba(10%2C10%2C10%2C0.65)\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbsee-through-2&#8243; color_override=\u00bb#000000&#8243; hover_color_override=\u00bb#DD3333&#8243; hover_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb url=\u00bbhttps:\/\/www.revelomallorca.es\/bike-rental-in-mallorca\/\u00bb text=\u00bbM\u00e1s informaci\u00f3n\u00bb margin_top=\u00bb32&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb delay=\u00bb100&#8243;][nectar_icon icon_family=\u00bbfontawesome\u00bb icon_style=\u00bbshadow-bg\u00bb icon_color_type=\u00bbcustom\u00bb icon_color_custom=\u00bb#000000&#8243; icon_color_custom_hover=\u00bb#DD3333&#8243; icon_padding=\u00bb20px\u00bb pointer_events=\u00bball\u00bb icon_fontawesome=\u00bbfa fa-shopping-bag\u00bb icon_size=\u00bb64&#8243; margin_bottom=\u00bb6&#8243;][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1759939248840{margin-top: 32px !important;margin-bottom: 15px !important;}\u00bb text_direction=\u00bbdefault\u00bb]\n<h5>Online Shop<\/h5>\n[\/vc_column_text][vc_custom_heading text=\u00bbUna l\u00ednea de productos para los amantes del ciclismo y de Mallorca. Dise\u00f1o de Revelo Mallorca.\u00bb font_container=\u00bbtag:p|text_align:center|color:rgba(10%2C10%2C10%2C0.65)\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbsee-through-2&#8243; color_override=\u00bb#000000&#8243; hover_color_override=\u00bb#DD3333&#8243; hover_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb url=\u00bbhttps:\/\/www.revelomallorca.es\/shop\/\u00bb text=\u00bbM\u00e1s informaci\u00f3n\u00bb margin_top=\u00bb32&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb delay=\u00bb200&#8243;][nectar_icon icon_family=\u00bbfontawesome\u00bb icon_style=\u00bbshadow-bg\u00bb icon_color_type=\u00bbcustom\u00bb icon_color_custom=\u00bb#000000&#8243; icon_color_custom_hover=\u00bb#DD3333&#8243; icon_padding=\u00bb20px\u00bb pointer_events=\u00bball\u00bb icon_fontawesome=\u00bbfa fa-coffee\u00bb icon_size=\u00bb64&#8243; margin_bottom=\u00bb6&#8243;][vc_column_text css_animation=\u00bbfadeInUp\u00bb css=\u00bb.vc_custom_1759939256868{margin-top: 32px !important;margin-bottom: 15px !important;}\u00bb text_direction=\u00bbdefault\u00bb]\n<h5>Cafeter\u00eda Revelo<\/h5>\n[\/vc_column_text][vc_custom_heading text=\u00bbNuestra cafeter\u00eda es un punto de encuentro donde se unen la pasi\u00f3n por el ciclismo y el buen gusto.\u00bb font_container=\u00bbtag:p|text_align:center|color:rgba(10%2C10%2C10%2C0.65)\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbfadeInUp\u00bb css=\u00bb\u00bb][nectar_btn size=\u00bblarge\u00bb button_style=\u00bbsee-through-2&#8243; color_override=\u00bb#000000&#8243; hover_color_override=\u00bb#DD3333&#8243; hover_text_color_override=\u00bb#ffffff\u00bb icon_family=\u00bbnone\u00bb url=\u00bbhttps:\/\/www.revelomallorca.es\/coffee-shop\/\u00bb text=\u00bbM\u00e1s informaci\u00f3n\u00bb margin_top=\u00bb32&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb2524&#8243; bg_position=\u00bbcenter top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#263336&#8243; overlay_strength=\u00bb1&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bb\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2207","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Revelo - Sobre nosotros - Revelo Mallorca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revelo - Sobre nosotros - Revelo Mallorca\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb2524&#8243; bg_position=\u00bbcenter top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#263336&#8243; overlay_strength=\u00bb1&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bb\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/\" \/>\n<meta property=\"og:site_name\" content=\"Revelo Mallorca\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T10:21:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/\",\"url\":\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/\",\"name\":\"Revelo - Sobre nosotros - Revelo Mallorca\",\"isPartOf\":{\"@id\":\"https:\/\/www.revelomallorca.es\/#website\"},\"datePublished\":\"2025-09-24T15:27:59+00:00\",\"dateModified\":\"2025-10-24T10:21:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.revelomallorca.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revelo &#8211; Sobre nosotros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.revelomallorca.es\/#website\",\"url\":\"https:\/\/www.revelomallorca.es\/\",\"name\":\"Revelo Mallorca - Bike Rental\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.revelomallorca.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.revelomallorca.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.revelomallorca.es\/#organization\",\"name\":\"Revelo Mallorca - Bike Rental\",\"url\":\"https:\/\/www.revelomallorca.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.revelomallorca.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.revelomallorca.es\/wp-content\/uploads\/2025\/09\/Revelo-logo-black.png\",\"contentUrl\":\"https:\/\/www.revelomallorca.es\/wp-content\/uploads\/2025\/09\/Revelo-logo-black.png\",\"width\":1188,\"height\":366,\"caption\":\"Revelo Mallorca - Bike Rental\"},\"image\":{\"@id\":\"https:\/\/www.revelomallorca.es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/revelomallorca\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revelo - Sobre nosotros - Revelo Mallorca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/","og_locale":"es_ES","og_type":"article","og_title":"Revelo - Sobre nosotros - Revelo Mallorca","og_description":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb2524&#8243; bg_position=\u00bbcenter top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#263336&#8243; overlay_strength=\u00bb1&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bb\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb...","og_url":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/","og_site_name":"Revelo Mallorca","article_modified_time":"2025-10-24T10:21:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/","url":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/","name":"Revelo - Sobre nosotros - Revelo Mallorca","isPartOf":{"@id":"https:\/\/www.revelomallorca.es\/#website"},"datePublished":"2025-09-24T15:27:59+00:00","dateModified":"2025-10-24T10:21:38+00:00","breadcrumb":{"@id":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.revelomallorca.es\/es\/revelo-sobre-nosotros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.revelomallorca.es\/es\/"},{"@type":"ListItem","position":2,"name":"Revelo &#8211; Sobre nosotros"}]},{"@type":"WebSite","@id":"https:\/\/www.revelomallorca.es\/#website","url":"https:\/\/www.revelomallorca.es\/","name":"Revelo Mallorca - Bike Rental","description":"","publisher":{"@id":"https:\/\/www.revelomallorca.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revelomallorca.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.revelomallorca.es\/#organization","name":"Revelo Mallorca - Bike Rental","url":"https:\/\/www.revelomallorca.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.revelomallorca.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.revelomallorca.es\/wp-content\/uploads\/2025\/09\/Revelo-logo-black.png","contentUrl":"https:\/\/www.revelomallorca.es\/wp-content\/uploads\/2025\/09\/Revelo-logo-black.png","width":1188,"height":366,"caption":"Revelo Mallorca - Bike Rental"},"image":{"@id":"https:\/\/www.revelomallorca.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/revelomallorca\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/pages\/2207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/comments?post=2207"}],"version-history":[{"count":10,"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/pages\/2207\/revisions"}],"predecessor-version":[{"id":2626,"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/pages\/2207\/revisions\/2626"}],"wp:attachment":[{"href":"https:\/\/www.revelomallorca.es\/es\/wp-json\/wp\/v2\/media?parent=2207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}